{"id":5891,"date":"2017-12-07T19:18:46","date_gmt":"2017-12-08T03:18:46","guid":{"rendered":"https:\/\/onewestmagazine.com\/magazine\/?p=5891"},"modified":"2017-12-07T19:18:46","modified_gmt":"2017-12-08T03:18:46","slug":"hot-new-video-philthy-rich-winning-team","status":"publish","type":"post","link":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/","title":{"rendered":"[HOT NEW VIDEO] PHILTHY RICH &#8211; WINNING TEAM"},"content":{"rendered":"<h4>New Video Alert!<\/h4>\n<p>For those who haven&#8217;t heard,\u00a0<strong>Philthy Rich\u00a0<\/strong>recently released a video for his song,\u00a0<strong>&#8220;Winning Team&#8221;,\u00a0<\/strong>which can be found on his latest project\u00a0<strong>&#8220;SEM GOD&#8221;<\/strong>.<\/p>\n<p>Watch it here first!<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>New Video Alert! For those who haven&#8217;t heard,\u00a0Philthy Rich\u00a0recently released a video for his song,\u00a0&#8220;Winning Team&#8221;,\u00a0which can be found on his latest project\u00a0&#8220;SEM GOD&#8221;. Watch it here first!<\/p>\n<\/div>","protected":false},"author":33,"featured_media":5892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[1586,2340,2339,2341],"class_list":["post-5891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-music","tag-philthy-rich","tag-sem-god","tag-the-sem-god","tag-winning-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM<\/title>\n<meta name=\"description\" content=\"New Video Alert! &quot;Winning Team&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM\" \/>\n<meta property=\"og:description\" content=\"New Video Alert! &quot;Winning Team&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\" \/>\n<meta property=\"og:site_name\" content=\"One West Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/onewestmagazine\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-08T03:18:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Samantha Willing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@onewestmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@onewestmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Samantha Willing\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\"},\"author\":{\"name\":\"Samantha Willing\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/f89d550bd18ecae561e1ac37b5f793e1\"},\"headline\":\"[HOT NEW VIDEO] PHILTHY RICH &#8211; WINNING TEAM\",\"datePublished\":\"2017-12-08T03:18:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\"},\"wordCount\":41,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#organization\"},\"image\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png\",\"keywords\":[\"philthy rich\",\"SEM GOD\",\"The Sem God\",\"Winning Team\"],\"articleSection\":[\"MUSIC\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\",\"url\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\",\"name\":\"[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM\",\"isPartOf\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png\",\"datePublished\":\"2017-12-08T03:18:46+00:00\",\"description\":\"New Video Alert! \\\"Winning Team\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage\",\"url\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png\",\"contentUrl\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png\",\"width\":1080,\"height\":473,\"caption\":\"Philthy Rich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/onewestmagazine.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[HOT NEW VIDEO] PHILTHY RICH &#8211; WINNING TEAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#website\",\"url\":\"https:\/\/onewestmagazine.com\/magazine\/\",\"name\":\"One West Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/onewestmagazine.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#organization\",\"name\":\"One West Magazine\",\"url\":\"https:\/\/onewestmagazine.com\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2016\/01\/header-logo02.jpg\",\"contentUrl\":\"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2016\/01\/header-logo02.jpg\",\"width\":362,\"height\":120,\"caption\":\"One West Magazine\"},\"image\":{\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/onewestmagazine\",\"https:\/\/x.com\/onewestmagazine\",\"https:\/\/www.instagram.com\/onewestmagazine\/\",\"https:\/\/www.youtube.com\/channel\/UCVS8gi-kW1TvSygC1oLHipA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/f89d550bd18ecae561e1ac37b5f793e1\",\"name\":\"Samantha Willing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edbc2c4410a37079e93a68fc5649256b53ce3da8d7afd4f771ff49c1a3a96f6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edbc2c4410a37079e93a68fc5649256b53ce3da8d7afd4f771ff49c1a3a96f6e?s=96&d=mm&r=g\",\"caption\":\"Samantha Willing\"},\"url\":\"https:\/\/onewestmagazine.com\/magazine\/author\/swilling\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM","description":"New Video Alert! \"Winning Team\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/","og_locale":"en_US","og_type":"article","og_title":"[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM","og_description":"New Video Alert! \"Winning Team\"","og_url":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/","og_site_name":"One West Magazine","article_publisher":"https:\/\/www.facebook.com\/onewestmagazine","article_published_time":"2017-12-08T03:18:46+00:00","og_image":[{"width":1080,"height":473,"url":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png","type":"image\/png"}],"author":"Samantha Willing","twitter_card":"summary_large_image","twitter_creator":"@onewestmagazine","twitter_site":"@onewestmagazine","twitter_misc":{"Written by":"Samantha Willing"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#article","isPartOf":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/"},"author":{"name":"Samantha Willing","@id":"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/f89d550bd18ecae561e1ac37b5f793e1"},"headline":"[HOT NEW VIDEO] PHILTHY RICH &#8211; WINNING TEAM","datePublished":"2017-12-08T03:18:46+00:00","mainEntityOfPage":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/"},"wordCount":41,"commentCount":0,"publisher":{"@id":"https:\/\/onewestmagazine.com\/magazine\/#organization"},"image":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage"},"thumbnailUrl":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png","keywords":["philthy rich","SEM GOD","The Sem God","Winning Team"],"articleSection":["MUSIC"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/","url":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/","name":"[HOT NEW VIDEO] PHILTHY RICH - WINNING TEAM","isPartOf":{"@id":"https:\/\/onewestmagazine.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage"},"image":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage"},"thumbnailUrl":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png","datePublished":"2017-12-08T03:18:46+00:00","description":"New Video Alert! \"Winning Team\"","breadcrumb":{"@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#primaryimage","url":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png","contentUrl":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2017\/12\/Screen-Shot-2017-12-07-at-9.40.43-PM.png","width":1080,"height":473,"caption":"Philthy Rich"},{"@type":"BreadcrumbList","@id":"https:\/\/onewestmagazine.com\/magazine\/hot-new-video-philthy-rich-winning-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onewestmagazine.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"[HOT NEW VIDEO] PHILTHY RICH &#8211; WINNING TEAM"}]},{"@type":"WebSite","@id":"https:\/\/onewestmagazine.com\/magazine\/#website","url":"https:\/\/onewestmagazine.com\/magazine\/","name":"One West Magazine","description":"","publisher":{"@id":"https:\/\/onewestmagazine.com\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onewestmagazine.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/onewestmagazine.com\/magazine\/#organization","name":"One West Magazine","url":"https:\/\/onewestmagazine.com\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2016\/01\/header-logo02.jpg","contentUrl":"https:\/\/onewestmagazine.com\/magazine\/wp-content\/uploads\/2016\/01\/header-logo02.jpg","width":362,"height":120,"caption":"One West Magazine"},"image":{"@id":"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/onewestmagazine","https:\/\/x.com\/onewestmagazine","https:\/\/www.instagram.com\/onewestmagazine\/","https:\/\/www.youtube.com\/channel\/UCVS8gi-kW1TvSygC1oLHipA"]},{"@type":"Person","@id":"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/f89d550bd18ecae561e1ac37b5f793e1","name":"Samantha Willing","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/onewestmagazine.com\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edbc2c4410a37079e93a68fc5649256b53ce3da8d7afd4f771ff49c1a3a96f6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edbc2c4410a37079e93a68fc5649256b53ce3da8d7afd4f771ff49c1a3a96f6e?s=96&d=mm&r=g","caption":"Samantha Willing"},"url":"https:\/\/onewestmagazine.com\/magazine\/author\/swilling\/"}]}},"_links":{"self":[{"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/posts\/5891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/comments?post=5891"}],"version-history":[{"count":1,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/posts\/5891\/revisions"}],"predecessor-version":[{"id":5893,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/posts\/5891\/revisions\/5893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/media\/5892"}],"wp:attachment":[{"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/media?parent=5891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/categories?post=5891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onewestmagazine.com\/magazine\/wp-json\/wp\/v2\/tags?post=5891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}